{"id":7083,"date":"2023-02-24T23:00:00","date_gmt":"2023-02-24T23:00:00","guid":{"rendered":"https:\/\/senhorcursos.com\/?p=7083"},"modified":"2023-02-24T19:47:03","modified_gmt":"2023-02-24T19:47:03","slug":"adicional-de-insalubridade","status":"publish","type":"post","link":"https:\/\/senhorcursos.com\/fr\/adicional-de-insalubridade\/","title":{"rendered":"Indemnit\u00e9 de risque maladie : qui y a droit et comment la calculer ?"},"content":{"rendered":"<!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-saiba-como-funciona-este-beneficio-trabalhista\">D\u00e9couvrez comment fonctionne cette allocation emploi<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large\"><img width=\"1024\" height=\"682\" loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156-1024x682.png\" alt=\"Soldador trabalha em ind\u00fastria\" class=\"w-full object-cover object-center border mx-auto wp-image-7084\" title=\"La prime de risque\" srcset=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156-1024x682.png 1024w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156-300x200.png 300w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156-768x512.png 768w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156.png 1060w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Les soudeurs font partie des professionnels qui b\u00e9n\u00e9ficient de cet avantage suppl\u00e9mentaire ! Rencontrez d\u2019autres. Source : Freepik.<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La prime de risque est une autre prestation dont un travailleur peut b\u00e9n\u00e9ficier en fonction des conditions dans lesquelles il exerce ses actions.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Cependant, savez-vous quelles sont les caract\u00e9ristiques d\u2019un travail malsain ? Ou quelle est la valeur de ces frais suppl\u00e9mentaires ?&nbsp;<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-1U4Q0h\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/fr\/demissao-por-justa-causa\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"Licenciement pour juste motif\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/01\/fired-businessman-feeling-worried-about-loosing-his-job-scaled.jpg\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/fr\/demissao-por-justa-causa\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"Licenciement pour juste motif\">\n            Licenciement pour juste motif        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            Que se passe-t-il lorsqu&#039;un travailleur est licenci\u00e9 pour un motif valable\u00a0? V\u00e9rifiez le ici.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/fr\/demissao-por-justa-causa\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuer la lecture            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/fr\/demissao-por-justa-causa\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/01\/fired-businessman-feeling-worried-about-loosing-his-job-scaled.jpg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Licenciement pour juste motif              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/fr\/demissao-por-justa-causa\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuer la lecture                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je me reposerai sur mon propre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Dans ce texte, nous r\u00e9pondrons aux principales questions sur ce sujet qui pr\u00e9occupe de nombreuses personnes.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Alors, si vous cherchez plus d\u2019informations, lisez notre guide complet jusqu\u2019\u00e0 la fin !<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-o-que-e-e-como-funciona-o-adicional-de-insalubridade\">Qu\u2019est-ce que la prime de risque et comment \u00e7a marche ?<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large\"><img width=\"1024\" height=\"682\" loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-157-1024x682.png\" alt=\"Homem trabalha em frigor\u00edfero \" class=\"w-full object-cover object-center border mx-auto wp-image-7085\" title=\"La prime de risque\" srcset=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-157-1024x682.png 1024w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-157-300x200.png 300w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-157-768x512.png 768w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-157.png 1060w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Comprendre les conditions pour que cet suppl\u00e9mentaire existe. Source : Freepik.<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La prime de risque est une prestation vers\u00e9e \u00e0 un groupe de travailleurs. Elle n\u2019est pas li\u00e9e \u00e0 la fonction ou au domaine d\u2019activit\u00e9, mais plut\u00f4t aux conditions de travail.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Vous avez des doutes et souhaitez des exemples de professions b\u00e9n\u00e9ficiant de cet avantage ? Reste calme! Nous vous expliquerons tout plus sereinement tout au long de l&#039;article.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Pour l&#039;instant, pr\u00e9cisons simplement que la prime de risque est vers\u00e9e sous la forme d&#039;une prime dans le salaire des salari\u00e9s qui en b\u00e9n\u00e9ficient.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Continuez \u00e0 lire pour savoir quels sont les montants et qui peut recevoir ce paiement suppl\u00e9mentaire.<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-Z17hfQm\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/fr\/adicional-noturno\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"Nuit suppl\u00e9mentaire\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-140.png\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/fr\/adicional-noturno\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"Nuit suppl\u00e9mentaire\">\n            Nuit suppl\u00e9mentaire        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            Connaissez-vous l\u2019avantage de travailler la nuit ? D\u00e9couvrez-le ici.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/fr\/adicional-noturno\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuer la lecture            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/fr\/adicional-noturno\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-140.png\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Nuit suppl\u00e9mentaire              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/fr\/adicional-noturno\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuer la lecture                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je me reposerai sur mon propre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-o-que-diz-a-clt-sobre-insalubridade\">Que dit le CLT des conditions insalubres ?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La prime pour travail insalubre a \u00e9t\u00e9 cr\u00e9\u00e9e par l&#039;article 189 du Consolidation des lois du travail (CLT).<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Cette loi d\u00e9finit que les personnes qui travaillent dans des activit\u00e9s ou dans des conditions qui causent des probl\u00e8mes de sant\u00e9 ont droit \u00e0 une allocation sur leur salaire.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Les probl\u00e8mes de sant\u00e9 peuvent \u00eatre caus\u00e9s par une exposition intense ou prolong\u00e9e \u00e0 des environnements nocifs.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Il convient de mentionner que le terme malsain signifie litt\u00e9ralement \u00ab ce qui n\u2019est pas bon pour la sant\u00e9 \u00bb.&nbsp;&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Il est donc important de diff\u00e9rencier cette prestation de la prime de risque, qui elle-m\u00eame est destin\u00e9e aux personnes qui exercent des professions dans lesquelles leur vie est menac\u00e9e.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Par cons\u00e9quent, dans les professions malsaines, il n\u2019y a aucun risque pour la vie. Cependant, l\u2019environnement de travail peut entra\u00eener divers pr\u00e9judices pour la sant\u00e9 des salari\u00e9s.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-quem-tem-direito-ao-adicional-de-insalubridade\">Qui a droit \u00e0 la prime de risque ?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Comme indiqu\u00e9 pr\u00e9c\u00e9demment, la prime de risque est vers\u00e9e aux personnes qui travaillent dans des endroits o\u00f9 les conditions sont pr\u00e9judiciables \u00e0 leur sant\u00e9.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Par exemple : des usines avec des bruits forts, qui peuvent entra\u00eener une perte auditive chez un employ\u00e9.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Dans le m\u00eame temps, l\u2019exposition aux temp\u00e9ratures \u00e9lev\u00e9es, au froid, \u00e0 l\u2019humidit\u00e9, aux poussi\u00e8res min\u00e9rales, aux poisons ou agents chimiques et aux rayonnements ionisants est \u00e9galement malsaine.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Un grand nombre d\u2019emplois peuvent donc \u00eatre inclus dans cette prestation. Par cons\u00e9quent, v\u00e9rifiez en ligne si votre position est consid\u00e9r\u00e9e comme malsaine.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Voici quelques exemples de professionnels qui b\u00e9n\u00e9ficient de cet avantage\u00a0:<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose text-left mb-5\">\n<ul><li>Travailleurs de diverses industries\u00a0;<\/li><li>Infirmi\u00e8res;<\/li><li>pr\u00e9pos\u00e9s aux stations-service;<\/li><li>Techniciens en radiologie\u00a0;<\/li><li>Ouvriers du conditionnement de la viande\u00a0;<\/li><li>Soudeurs.<\/li><\/ul>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-qual-o-valor-do-adicional-de-insalubridade\">Quelle est la valeur de la prime de risque ?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Les montants de la prime de risque varient en fonction du niveau de risque auquel un salari\u00e9 est confront\u00e9 dans son environnement de travail.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Ainsi, dans les entreprises o\u00f9 les dommages \u00e0 la sant\u00e9 sont faibles, le montant suppl\u00e9mentaire est de 10%. En revanche, si le niveau de perte est moyen, le bonus est de 20%. Enfin, en cas de risque sanitaire majeur, le montant suppl\u00e9mentaire est de 40%.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Les juges et les techniciens du travail d\u00e9finissent \u00e0 quelle cat\u00e9gorie appartient une entreprise. Par cons\u00e9quent, v\u00e9rifiez le niveau de conditions insalubres sur votre lieu de travail.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-como-calcular-o-adicional-de-insalubridade\">Comment calculer la prime de risque ?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La loi ne pr\u00e9cise pas sur quelle base doit \u00eatre calcul\u00e9e la prime de risque.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Une entreprise peut donc utiliser diff\u00e9rentes bases. Par exemple : le salaire minimum actuel, le salaire minimum de la cat\u00e9gorie, le salaire des travailleurs ou d&#039;autres valeurs.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Il est donc n\u00e9cessaire de savoir sur quelle base l\u2019entreprise pour laquelle vous travaillez utilise pour effectuer ce calcul. Ensuite, d\u00e9couvrez quel est le niveau de conditions insalubres sur votre lieu de travail.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Enfin, multipliez simplement la valeur de base utilis\u00e9e par le pourcentage \u00e9quivalent et vous obtiendrez la valeur de votre prestation.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-como-verificar-o-pagamento-desse-adicional\">Comment puis-je v\u00e9rifier le paiement de ce montant suppl\u00e9mentaire ?<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large\"><img width=\"1024\" height=\"683\" loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-158-1024x683.png\" alt=\"Pessoa usa calculadora para checar valor do Adicional de insalubridade\" class=\"w-full object-cover object-center border mx-auto wp-image-7086\" title=\"La prime de risque\" srcset=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-158-1024x683.png 1024w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-158-300x200.png 300w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-158-768x512.png 768w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-158.png 1060w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Le calcul d\u00e9pend de plusieurs facteurs, sachez de quoi il s\u2019agit. Source : Freepik.<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Pour s&#039;assurer que la prime de risque est effectivement vers\u00e9e, une personne peut demander \u00e0 son superviseur quel est son salaire de base. V\u00e9rifiez ensuite les ajouts.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Si vous constatez des valeurs incorrectes, une solution consiste \u00e0 contacter le syndicat de votre r\u00e9gion. Cette institution peut \u00e9galement vous aider \u00e0 comprendre si le niveau malsain est calcul\u00e9 correctement.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Enfin, si vous r\u00e9alisez que votre profession ne devrait pas b\u00e9n\u00e9ficier de cette prestation, mais plut\u00f4t d&#039;une prime de risque, lisez notre texte sur le th\u00e8me indiqu\u00e9 ci-dessous.\u00a0<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Nous pouvons vous aider \u00e0 mieux comprendre les conditions dans lesquelles cette prime est vers\u00e9e et quels professionnels la per\u00e7oivent.<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-1vi0BN\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/fr\/adicional-de-periculosidade\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"Prime de risque suppl\u00e9mentaire\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-146.png\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/fr\/adicional-de-periculosidade\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"Prime de risque suppl\u00e9mentaire\">\n            Prime de risque suppl\u00e9mentaire        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            D\u00e9couvrez quelles professions b\u00e9n\u00e9ficient de cet avantage.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/fr\/adicional-de-periculosidade\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuer la lecture            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/fr\/adicional-de-periculosidade\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-146.png\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Prime de risque suppl\u00e9mentaire              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/fr\/adicional-de-periculosidade\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuer la lecture                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je me reposerai sur mon propre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La prime de risque est vers\u00e9e aux travailleurs qui travaillent dans des conditions pr\u00e9judiciables \u00e0 leur sant\u00e9 ! D\u00e9couvrez de quoi il s\u2019agit et d\u00e9couvrez le montant pay\u00e9.<\/p>","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[281],"tags":[439,442,269],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.7 (Yoast SEO v19.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adicional de insalubridade: quem tem direito e como calcular? - Senhor Cursos<\/title>\n<meta name=\"description\" content=\"Voc\u00ea sabe quais s\u00e3o as profiss\u00f5es que tem direito ao adicional de insalubridade? Neste guia vamos te ajudar a entender tudo sobre o tema!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/senhorcursos.com\/fr\/adicional-de-insalubridade\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adicional de insalubridade: quem tem direito e como calcular?\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea sabe quais s\u00e3o as profiss\u00f5es que tem direito ao adicional de insalubridade? Neste guia vamos te ajudar a entender tudo sobre o tema!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/senhorcursos.com\/fr\/adicional-de-insalubridade\/\" \/>\n<meta property=\"og:site_name\" content=\"Senhor Cursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-24T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-24T19:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156-1024x682.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Saes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/senhorcursos.com\/#website\",\"url\":\"https:\/\/senhorcursos.com\/\",\"name\":\"Senhor Cursos\",\"description\":\"Os melhores cursos, concursos e vagas de empregos para voc\u00ea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/senhorcursos.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#primaryimage\",\"url\":\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156.png\",\"contentUrl\":\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156.png\",\"width\":1060,\"height\":706},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#webpage\",\"url\":\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/\",\"name\":\"Adicional de insalubridade: quem tem direito e como calcular? - Senhor Cursos\",\"isPartOf\":{\"@id\":\"https:\/\/senhorcursos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#primaryimage\"},\"datePublished\":\"2023-02-24T23:00:00+00:00\",\"dateModified\":\"2023-02-24T19:47:03+00:00\",\"author\":{\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2\"},\"description\":\"Voc\u00ea sabe quais s\u00e3o as profiss\u00f5es que tem direito ao adicional de insalubridade? Neste guia vamos te ajudar a entender tudo sobre o tema!\",\"breadcrumb\":{\"@id\":\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/senhorcursos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adicional de insalubridade: quem tem direito e como calcular?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2\",\"name\":\"Aline Saes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"caption\":\"Aline Saes\"},\"url\":\"https:\/\/senhorcursos.com\/fr\/author\/aline-saes-rodriguesgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adicional de insalubridade: quem tem direito e como calcular? - Senhor Cursos","description":"Voc\u00ea sabe quais s\u00e3o as profiss\u00f5es que tem direito ao adicional de insalubridade? Neste guia vamos te ajudar a entender tudo sobre o tema!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/senhorcursos.com\/fr\/adicional-de-insalubridade\/","og_locale":"fr_FR","og_type":"article","og_title":"Adicional de insalubridade: quem tem direito e como calcular?","og_description":"Voc\u00ea sabe quais s\u00e3o as profiss\u00f5es que tem direito ao adicional de insalubridade? Neste guia vamos te ajudar a entender tudo sobre o tema!","og_url":"https:\/\/senhorcursos.com\/fr\/adicional-de-insalubridade\/","og_site_name":"Senhor Cursos","article_published_time":"2023-02-24T23:00:00+00:00","article_modified_time":"2023-02-24T19:47:03+00:00","og_image":[{"url":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156-1024x682.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aline Saes","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/senhorcursos.com\/#website","url":"https:\/\/senhorcursos.com\/","name":"Senhor Cursos","description":"Os melhores cursos, concursos e vagas de empregos para voc\u00ea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/senhorcursos.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#primaryimage","url":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156.png","contentUrl":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/02\/image-156.png","width":1060,"height":706},{"@type":"WebPage","@id":"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#webpage","url":"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/","name":"Adicional de insalubridade: quem tem direito e como calcular? - Senhor Cursos","isPartOf":{"@id":"https:\/\/senhorcursos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#primaryimage"},"datePublished":"2023-02-24T23:00:00+00:00","dateModified":"2023-02-24T19:47:03+00:00","author":{"@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2"},"description":"Voc\u00ea sabe quais s\u00e3o as profiss\u00f5es que tem direito ao adicional de insalubridade? Neste guia vamos te ajudar a entender tudo sobre o tema!","breadcrumb":{"@id":"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/senhorcursos.com\/adicional-de-insalubridade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/senhorcursos.com\/adicional-de-insalubridade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/senhorcursos.com\/"},{"@type":"ListItem","position":2,"name":"Adicional de insalubridade: quem tem direito e como calcular?"}]},{"@type":"Person","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2","name":"Aline Saes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","caption":"Aline Saes"},"url":"https:\/\/senhorcursos.com\/fr\/author\/aline-saes-rodriguesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts\/7083"}],"collection":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/comments?post=7083"}],"version-history":[{"count":0,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts\/7083\/revisions"}],"wp:attachment":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/media?parent=7083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/categories?post=7083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/tags?post=7083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}