{"id":13653,"date":"2024-03-01T13:10:02","date_gmt":"2024-03-01T13:10:02","guid":{"rendered":"https:\/\/senhorcursos.com\/?p=13653"},"modified":"2024-03-08T16:11:06","modified_gmt":"2024-03-08T16:11:06","slug":"emprego-kraft-heinz","status":"publish","type":"post","link":"https:\/\/senhorcursos.com\/fr\/emprego-kraft-heinz\/","title":{"rendered":"Emploi chez Kraft Heinz : consultez les opportunit\u00e9s disponibles"},"content":{"rendered":"<!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-junte-se-a-familia-kraft-heinz-e-faca-parte-de-um-sucesso-global\"><strong>Rejoignez la famille Kraft Heinz et faites partie d&#039;un succ\u00e8s mondial<\/strong><\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg\" alt=\"Confira tudo sobre a vaga de emprego na Kraft Heinz.\" class=\"w-full object-cover object-center border mx-auto wp-image-741\" width=\"800\" height=\"384\"\/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Trouvez un emploi gr\u00e2ce \u00e0 Kraft Heinz. Source : Adobe Stock<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Dans un monde o\u00f9 la recherche d&#039;une carri\u00e8re significative devient de plus en plus une priorit\u00e9, l&#039;emploi chez Kraft Heinz se pr\u00e9sente comme une formidable opportunit\u00e9.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>L&#039;entreprise, connue dans le monde entier pour ses marques embl\u00e9matiques et ses produits de haute qualit\u00e9, offre bien plus que des emplois ; cela promet un parcours de croissance, d\u2019apprentissage et, surtout, une chance de faire la diff\u00e9rence.&nbsp;<\/p>\n<\/div><div class=\"wp-block-lazyblock-credit-card lazyblock-credit-card-Z2hUhuN\"><section class=\"credit-card mx-5 sm:mx-0 text-gray-600 body-font  my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n  <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n    <div class=\"w-24 h-full\"><\/div>\n  <\/div>\n  <div class=\"container px-5 sm:px-0 py-6 mx-auto\" data-anchor-target=\"lazyBlock\">\n    <div class=\"flex flex-wrap mx-auto\">\n      <a class=\"lg:w-2\/5 w-full lg:pl-6 mt-6 lg:mt-0\" href=\"https:\/\/careers.kraftheinz.com\/\" data-analytics-label=\"creditCardImage\" data-action=\"analytics#trackCTA\" >\n        <img class=\"w-full h-64 object-cover object-center rounded\" loading=\"lazy\" alt=\"card\" style=\"height: 190px;\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-1-scaled.jpeg\">\n      <\/a>\n      <div class=\"lg:w-3\/5 w-full lg:pl-6 mt-6 lg:mt-0\">\n        <h2 class=\"text-sm title-font text-gray-500 tracking-widest uppercase\">\n          site        <\/h2>\n        <h1 class=\"text-gray-900 text-3xl title-font font-medium mb-1\">\n          Kraft-Heinz         <\/h1>\n        <div class=\"flex mb-4 justify-center sm:justify-start\">\n          \n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              offres d&#039;emploi            <\/span>\n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              opportunit\u00e9            <\/span>\n                    \n        <\/div>\n        <p class=\"leading-relaxed\">\n          Acc\u00e9dez au site Web de Kraft Heinz et recherchez d\u00e8s maintenant votre offre d&#039;emploi id\u00e9ale.        <\/p>\n        <div class=\"flex mt-6 items-center pb-5 border-b-2 border-gray-100 mb-5\">\n          \n        <\/div>\n        <div class=\"flex\">\n          <a data-km2-rewarded=\"true\" style=\"font-size: 13px;\" class=\"hidden animate-fade-in flex m-auto sm:mr-0 sm:ml-auto\" rel=\"sponsored\" href=\"https:\/\/careers.kraftheinz.com\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button class=\"uppercase flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-4 focus:outline-none rounded  disabled:opacity-50\">\n              VOIR LES POSTES VACANTS            <\/button>\n          <\/a>\n          <a data-km2-rewarded=\"false\" style=\"font-size: 15px;\" class=\"flex m-auto sm:mr-0 sm:ml-auto\" rel=\"sponsored\" href=\"https:\/\/careers.kraftheinz.com\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button id=\"offer-first\" class=\"flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-6 focus:outline-none rounded  disabled:opacity-50\">\n              VOIR LES POSTES VACANTS            <\/button>\n          <\/a>\n        <\/div>\n        <p class=\"text-xs text-gray-500 mt-3 text-center sm:text-right\">\n          Je serai redirig\u00e9 vers un autre site Web        <\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/careers.kraftheinz.com\/\" rel=\"sponsored\" data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-1-scaled.jpeg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Acc\u00e9dez au site Web de Kraft Heinz et recherchez votre offre d&#039;emploi\u2026              <\/p>\n              <a href=\"https:\/\/careers.kraftheinz.com\/\" rel=\"sponsored\" data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    VOIR LES POSTES VACANTS                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je serai redirig\u00e9 vers un autre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/section><\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Mais qu\u2019est-ce qui fait de Kraft Heinz un lieu de travail si sp\u00e9cial ? Quelle est la culture de votre organisation ? Quelles zones sont actuellement disponibles ?<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Maintenant, dans cet article, nous aborderons ces questions et d&#039;autres afin que vous ayez des r\u00e9ponses \u00e0 vos questions et que vous soyez pr\u00eat \u00e0 faire le premier pas vers une carri\u00e8re chez Kraft Heinz !<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-o-que-e-a-kraft-heinz\"><strong>Qu\u2019est-ce que Kraft Heinz ?<\/strong><\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Kraft Heinz n&#039;est pas seulement l&#039;une des plus grandes entreprises agroalimentaires au monde. Apr\u00e8s tout, c\u2019est une institution fi\u00e8re de ses racines historiques, tout en regardant vers l\u2019avenir avec innovation et strat\u00e9gie.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Avec un portefeuille comprenant plus de 200 marques mondiales et locales, l&#039;entreprise s&#039;efforce de nourrir la vie avec une alimentation de qualit\u00e9.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>De plus, Kraft Heinz est synonyme d&#039;excellence op\u00e9rationnelle, de durabilit\u00e9 et de responsabilit\u00e9 sociale, attributs qui en font un leader du secteur.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-qual-e-a-cultura-organizacional-da-kraft-heinz\"><strong>Quelle est la culture organisationnelle chez Kraft Heinz?<\/strong><\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_312500406_Editorial_Use_Only-1024x683.jpeg\" alt=\"\" class=\"w-full object-cover object-center border mx-auto wp-image-745\" width=\"800\" height=\"384\"\/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Trouvez l&#039;emploi de vos r\u00eaves. Source : Adobe Stock<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La culture de Kraft Heinz est une fusion unique de tradition et d&#039;innovation. En mettant l&#039;accent sur la m\u00e9ritocratie, l&#039;entreprise encourage tous ses employ\u00e9s \u00e0 \u00eatre les meilleurs dans leur domaine, en promouvant un environnement de travail o\u00f9 l&#039;excellence est la norme.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Sans oublier que la diversit\u00e9 est bien plus que de simples mots chez Kraft Heinz ; Ce sont des pratiques v\u00e9cues au quotidien, garantissant que chaque voix soit entendue et valoris\u00e9e.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>En fin de compte, cette culture dynamique est aliment\u00e9e par des valeurs fondamentales d\u2019int\u00e9grit\u00e9, de qualit\u00e9 et de respect, cr\u00e9ant un environnement o\u00f9 chacun est encourag\u00e9 \u00e0 grandir et \u00e0 prosp\u00e9rer.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-conheca-as-areas-de-trabalho-da-kraft-heinz\"><strong>D\u00e9couvrez les espaces de travail de Kraft Heinz<\/strong><\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Tout d\u2019abord, dans cette entreprise, ils offrent de larges opportunit\u00e9s de carri\u00e8re, qui couvrent diverses disciplines et sp\u00e9cialisations.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Ainsi, si vous \u00eates passionn\u00e9 par l&#039;innovation num\u00e9rique, la finance, les technologies de l&#039;information, le marketing, la fabrication, les ventes, la recherche et le d\u00e9veloppement ou la gestion des ressources humaines et des performances, Kraft Heinz a une place pour vous. Regarder:<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-digital\"><strong>Num\u00e9rique<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Au c\u0153ur de la transformation num\u00e9rique de Kraft Heinz, cette \u00e9quipe travaille \u00e0 r\u00e9volutionner la fa\u00e7on dont l&#039;entreprise se connecte avec ses consommateurs et optimise ses op\u00e9rations internes.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-contabilidade-e-financas\"><strong>Comptabilit\u00e9 et finance<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Essentiel au succ\u00e8s durable de l&#039;entreprise, l&#039;emploi dans ce domaine garantit la sant\u00e9 financi\u00e8re de Kraft Heinz, g\u00e8re les risques et identifie les opportunit\u00e9s de croissance.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-tecnologia-da-informacao\"><strong>Informatique<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>L&#039;\u00e9quipe informatique est l&#039;\u00e9pine dorsale qui soutient toutes les op\u00e9rations de l&#039;entreprise. C&#039;est-\u00e0-dire, de la production \u00e0 la livraison, en garantissant que l&#039;innovation et l&#039;efficacit\u00e9 soient toujours pr\u00e9sentes.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-marketing\"><strong>Commercialisation<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Responsable de la construction et du maintien de la force des marques Kraft Heinz, ce secteur s&#039;efforce de comprendre et de r\u00e9pondre aux besoins des consommateurs, en cr\u00e9ant des campagnes qui dynamisent et engagent l&#039;entreprise.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-fabricacao\"><strong>Fabrication<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Cette zone est sans aucun doute le c\u0153ur de l&#039;op\u00e9ration, o\u00f9 la qualit\u00e9 des produits Kraft Heinz est toujours garantie. En fait, cette \u00e9quipe travaille sans rel\u00e2che pour s&#039;assurer que chaque article r\u00e9pond aux plus hauts standards de s\u00e9curit\u00e9 et d&#039;excellence.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-vendas\"><strong>Ventes<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>L&#039;\u00e9quipe commerciale est le moteur qui anime Kraft Heinz, \u00e9tablissant des partenariats durables avec les clients et les consommateurs. Par cons\u00e9quent, en adoptant une approche strat\u00e9gique, ce groupe est toujours \u00e0 la recherche de nouvelles fa\u00e7ons de cro\u00eetre et d&#039;innover sur le march\u00e9.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-pesquisa-e-desenvolvimento\"><strong>Recherche et d\u00e9veloppement<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>L\u2019innovation est essentielle dans ce domaine. Apr\u00e8s tout, c\u2019est l\u00e0 que de nouveaux produits sont cr\u00e9\u00e9s et que ceux existants sont am\u00e9lior\u00e9s, toujours dans le but de mieux r\u00e9pondre aux demandes des consommateurs.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-pessoas-e-desempenho\"><strong>Personnes et performances<\/strong><\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Ax\u00e9 sur l&#039;attraction, le d\u00e9veloppement et la r\u00e9tention des meilleurs talents, l&#039;emploi dans ce domaine est essentiel pour garantir que Kraft Heinz continue d&#039;\u00eatre un lieu de travail incroyable.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-veja-como-fazer-a-sua-candidatura-para-a-kraft-heinz\"><strong>D\u00e9couvrez comment postuler \u00e0 Kraft Heinz<\/strong><\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-5-1024x576.jpeg\" alt=\"\" class=\"w-full object-cover object-center border mx-auto wp-image-13659\" width=\"800\" height=\"384\"\/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Votre carri\u00e8re dans cette entreprise mondiale n\u2019est qu\u2019\u00e0 quelques pas. Source : Adobe Stock<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Si vous recherchez une carri\u00e8re qui offre plus qu&#039;un simple emploi, mais une opportunit\u00e9 de faire partie de quelque chose de plus grand, le poste de Kraft Heinz est fait pour vous.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Tout d&#039;abord, pour postuler, visitez le site officiel des carri\u00e8res de Kraft Heinz en cliquant sur le lien ci-dessous et explorez les postes disponibles qui correspondent \u00e0 vos comp\u00e9tences et vos passions.&nbsp;<\/p>\n<\/div><div class=\"wp-block-lazyblock-credit-card lazyblock-credit-card-Z4BFpG\"><section class=\"credit-card mx-5 sm:mx-0 text-gray-600 body-font  my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n  <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n    <div class=\"w-24 h-full\"><\/div>\n  <\/div>\n  <div class=\"container px-5 sm:px-0 py-6 mx-auto\" data-anchor-target=\"lazyBlock\">\n    <div class=\"flex flex-wrap mx-auto\">\n      <a class=\"lg:w-2\/5 w-full lg:pl-6 mt-6 lg:mt-0\" href=\"https:\/\/careers.kraftheinz.com\/\" data-analytics-label=\"creditCardImage\" data-action=\"analytics#trackCTA\" >\n        <img class=\"w-full h-64 object-cover object-center rounded\" loading=\"lazy\" alt=\"card\" style=\"height: 190px;\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-2-scaled.jpeg\">\n      <\/a>\n      <div class=\"lg:w-3\/5 w-full lg:pl-6 mt-6 lg:mt-0\">\n        <h2 class=\"text-sm title-font text-gray-500 tracking-widest uppercase\">\n          site        <\/h2>\n        <h1 class=\"text-gray-900 text-3xl title-font font-medium mb-1\">\n          Kraft-Heinz         <\/h1>\n        <div class=\"flex mb-4 justify-center sm:justify-start\">\n          \n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              offres d&#039;emploi            <\/span>\n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              Kraft-Heinz            <\/span>\n                    \n        <\/div>\n        <p class=\"leading-relaxed\">\n          Acc\u00e9dez au site Web de Kraft Heinz et trouvez une opportunit\u00e9 d&#039;emploi.        <\/p>\n        <div class=\"flex mt-6 items-center pb-5 border-b-2 border-gray-100 mb-5\">\n          \n        <\/div>\n        <div class=\"flex\">\n          <a data-km2-rewarded=\"true\" style=\"font-size: 13px;\" class=\"hidden animate-fade-in flex m-auto sm:mr-0 sm:ml-auto\" rel=\"sponsored\" href=\"https:\/\/careers.kraftheinz.com\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button class=\"uppercase flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-4 focus:outline-none rounded  disabled:opacity-50\">\n              ACC\u00c9DER AUX POSTES VACANTS            <\/button>\n          <\/a>\n          <a data-km2-rewarded=\"false\" style=\"font-size: 15px;\" class=\"flex m-auto sm:mr-0 sm:ml-auto\" rel=\"sponsored\" href=\"https:\/\/careers.kraftheinz.com\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button id=\"offer-first\" class=\"flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-6 focus:outline-none rounded  disabled:opacity-50\">\n              ACC\u00c9DER AUX POSTES VACANTS            <\/button>\n          <\/a>\n        <\/div>\n        <p class=\"text-xs text-gray-500 mt-3 text-center sm:text-right\">\n          Je serai redirig\u00e9 vers un autre site Web        <\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/careers.kraftheinz.com\/\" rel=\"sponsored\" data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-2-scaled.jpeg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Entrez sur le site Web de Kraft Heinz et trouvez une opportunit\u00e9 de\u2026              <\/p>\n              <a href=\"https:\/\/careers.kraftheinz.com\/\" rel=\"sponsored\" data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    ACC\u00c9DER AUX POSTES VACANTS                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je serai redirig\u00e9 vers un autre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/section><\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Ensuite, une fois que vous avez trouv\u00e9 une offre d&#039;emploi chez Kraft Heinz qui correspond \u00e0 vos pr\u00e9f\u00e9rences et comp\u00e9tences, suivez le processus de connexion au site Web et postulez pour le poste.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Enfin, le processus de candidature est simple et direct, encourageant les candidats issus de divers horizons \u00e0 apporter leurs talents uniques \u00e0 l&#039;\u00e9quipe.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Si vous avez aim\u00e9 cet article et souhaitez un didacticiel plus d\u00e9taill\u00e9 sur la fa\u00e7on de postuler \u00e0 l&#039;un de ces emplois, cliquez sur le lien ci-dessous.<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-2sfzmb\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/fr\/kraft-heinz-careers\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"Carri\u00e8res chez Kraft Heinz\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-4-scaled.jpeg\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/fr\/kraft-heinz-careers\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"Carri\u00e8res chez Kraft Heinz\">\n            Carri\u00e8res chez Kraft Heinz        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            D\u00e9couvrez comment postuler \u00e0 un emploi chez Kraft Heinz pour une carri\u00e8re r\u00e9ussie.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/fr\/kraft-heinz-careers\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuer la lecture            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/fr\/kraft-heinz-careers\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2024\/03\/kraft-heinz-4-scaled.jpeg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Carri\u00e8res chez Kraft Heinz              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/fr\/kraft-heinz-careers\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuer la lecture                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je me reposerai sur mon propre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Trouvez une carri\u00e8re unique chez Kraft Heinz, o\u00f9 diversit\u00e9, innovation et croissance se rencontrent pour cr\u00e9er des opportunit\u00e9s illimit\u00e9es. Rejoignez l&#039;\u00e9quipe aujourd&#039;hui et faites partie de la famille. <\/p>","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[281,282],"tags":[812,814,813],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.7 (Yoast SEO v19.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emprego na Kraft Heinz: confira as oportunidades - Senhor Cursos<\/title>\n<meta name=\"description\" content=\"Fa\u00e7a parte da equipe com o emprego na Kraft Heinz e transforme seu futuro. Leia o artigo agora e conhe\u00e7a as vagas que te esperam!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/senhorcursos.com\/fr\/emprego-kraft-heinz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emprego na Kraft Heinz: confira as oportunidades dispon\u00edveis\" \/>\n<meta property=\"og:description\" content=\"Fa\u00e7a parte da equipe com o emprego na Kraft Heinz e transforme seu futuro. Leia o artigo agora e conhe\u00e7a as vagas que te esperam!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/senhorcursos.com\/fr\/emprego-kraft-heinz\/\" \/>\n<meta property=\"og:site_name\" content=\"Senhor Cursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T13:10:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T16:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Saes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/senhorcursos.com\/#website\",\"url\":\"https:\/\/senhorcursos.com\/\",\"name\":\"Senhor Cursos\",\"description\":\"Os melhores cursos, concursos e vagas de empregos para voc\u00ea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/senhorcursos.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#primaryimage\",\"url\":\"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg\",\"contentUrl\":\"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#webpage\",\"url\":\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/\",\"name\":\"Emprego na Kraft Heinz: confira as oportunidades - Senhor Cursos\",\"isPartOf\":{\"@id\":\"https:\/\/senhorcursos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#primaryimage\"},\"datePublished\":\"2024-03-01T13:10:02+00:00\",\"dateModified\":\"2024-03-08T16:11:06+00:00\",\"author\":{\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2\"},\"description\":\"Fa\u00e7a parte da equipe com o emprego na Kraft Heinz e transforme seu futuro. Leia o artigo agora e conhe\u00e7a as vagas que te esperam!\",\"breadcrumb\":{\"@id\":\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/senhorcursos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emprego na Kraft Heinz: confira as oportunidades dispon\u00edveis\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2\",\"name\":\"Aline Saes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"caption\":\"Aline Saes\"},\"url\":\"https:\/\/senhorcursos.com\/fr\/author\/aline-saes-rodriguesgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Emprego na Kraft Heinz: confira as oportunidades - Senhor Cursos","description":"Fa\u00e7a parte da equipe com o emprego na Kraft Heinz e transforme seu futuro. Leia o artigo agora e conhe\u00e7a as vagas que te esperam!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/senhorcursos.com\/fr\/emprego-kraft-heinz\/","og_locale":"fr_FR","og_type":"article","og_title":"Emprego na Kraft Heinz: confira as oportunidades dispon\u00edveis","og_description":"Fa\u00e7a parte da equipe com o emprego na Kraft Heinz e transforme seu futuro. Leia o artigo agora e conhe\u00e7a as vagas que te esperam!","og_url":"https:\/\/senhorcursos.com\/fr\/emprego-kraft-heinz\/","og_site_name":"Senhor Cursos","article_published_time":"2024-03-01T13:10:02+00:00","article_modified_time":"2024-03-08T16:11:06+00:00","og_image":[{"url":"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aline Saes","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/senhorcursos.com\/#website","url":"https:\/\/senhorcursos.com\/","name":"Senhor Cursos","description":"Os melhores cursos, concursos e vagas de empregos para voc\u00ea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/senhorcursos.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#primaryimage","url":"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg","contentUrl":"https:\/\/seujobs.com\/wp-content\/uploads\/2024\/02\/AdobeStock_516014672_Editorial_Use_Only-1024x539.jpeg"},{"@type":"WebPage","@id":"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#webpage","url":"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/","name":"Emprego na Kraft Heinz: confira as oportunidades - Senhor Cursos","isPartOf":{"@id":"https:\/\/senhorcursos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#primaryimage"},"datePublished":"2024-03-01T13:10:02+00:00","dateModified":"2024-03-08T16:11:06+00:00","author":{"@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2"},"description":"Fa\u00e7a parte da equipe com o emprego na Kraft Heinz e transforme seu futuro. Leia o artigo agora e conhe\u00e7a as vagas que te esperam!","breadcrumb":{"@id":"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/senhorcursos.com\/emprego-kraft-heinz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/senhorcursos.com\/emprego-kraft-heinz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/senhorcursos.com\/"},{"@type":"ListItem","position":2,"name":"Emprego na Kraft Heinz: confira as oportunidades dispon\u00edveis"}]},{"@type":"Person","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2","name":"Aline Saes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","caption":"Aline Saes"},"url":"https:\/\/senhorcursos.com\/fr\/author\/aline-saes-rodriguesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts\/13653"}],"collection":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/comments?post=13653"}],"version-history":[{"count":0,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts\/13653\/revisions"}],"wp:attachment":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/media?parent=13653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/categories?post=13653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/tags?post=13653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}