{"id":12230,"date":"2023-09-11T12:15:53","date_gmt":"2023-09-11T12:15:53","guid":{"rendered":"https:\/\/senhorcursos.com\/?p=12230"},"modified":"2023-09-13T19:39:15","modified_gmt":"2023-09-13T19:39:15","slug":"design-de-sobrancelhas","status":"publish","type":"post","link":"https:\/\/senhorcursos.com\/fr\/design-de-sobrancelhas\/","title":{"rendered":"Design des sourcils : comment devenir un professionnel dans le domaine"},"content":{"rendered":"<!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-torne-se-uma-profissional-de-destaque-como-designer-de-sobrancelhas\">Devenez un professionnel de premier plan en tant que cr\u00e9ateur de sourcils\u00a0!<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg\" alt=\"\" class=\"w-full object-cover object-center border mx-auto wp-image-12231\" width=\"800\" height=\"384\"\/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >D\u00e9couvrez les secrets de la conception des sourcils. Source : Adobe Stock<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Les sourcils jouent un r\u00f4le fondamental, car ils fa\u00e7onnent le visage et d\u00e9finissent notre apparence. Que vous soyez passionn\u00e9 de beaut\u00e9 ou artiste en herbe, la mise en forme des sourcils change la vie.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>En fait, si vous pensez que devenir Designer de Sourcils pourrait changer votre carri\u00e8re, profitez-en pour vous renseigner d\u00e8s maintenant sur les options de cours. Cliquez sur le lien ci-dessous.<\/p>\n<\/div><div class=\"wp-block-lazyblock-credit-card lazyblock-credit-card-Z1IKOtM\"><section class=\"credit-card mx-5 sm:mx-0 text-gray-600 body-font  my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n  <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n    <div class=\"w-24 h-full\"><\/div>\n  <\/div>\n  <div class=\"container px-5 sm:px-0 py-6 mx-auto\" data-anchor-target=\"lazyBlock\">\n    <div class=\"flex flex-wrap mx-auto\">\n      <a class=\"lg:w-2\/5 w-full lg:pl-6 mt-6 lg:mt-0\" href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\" data-analytics-label=\"creditCardImage\" data-action=\"analytics#trackCTA\" >\n        <img class=\"w-full h-64 object-cover object-center rounded\" loading=\"lazy\" alt=\"card\" style=\"height: 190px;\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-1-scaled.jpeg\">\n      <\/a>\n      <div class=\"lg:w-3\/5 w-full lg:pl-6 mt-6 lg:mt-0\">\n        <h2 class=\"text-sm title-font text-gray-500 tracking-widest uppercase\">\n          Article        <\/h2>\n        <h1 class=\"text-gray-900 text-3xl title-font font-medium mb-1\">\n          Cours de conception de sourcils        <\/h1>\n        <div class=\"flex mb-4 justify-center sm:justify-start\">\n          \n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              cours de designer            <\/span>\n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              les sourcils            <\/span>\n                    \n        <\/div>\n        <p class=\"leading-relaxed\">\n          Transformez votre carri\u00e8re avec des cours d&#039;\u00e9lite en mati\u00e8re de conception de sourcils.         <\/p>\n        <div class=\"flex mt-6 items-center pb-5 border-b-2 border-gray-100 mb-5\">\n          \n        <\/div>\n        <div class=\"flex\">\n          <a data-km2-rewarded=\"true\" style=\"font-size: 13px;\" class=\"hidden animate-fade-in flex m-auto sm:mr-0 sm:ml-auto\"  href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button class=\"uppercase flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-4 focus:outline-none rounded  disabled:opacity-50\">\n              ACC\u00c9DER \u00c0 L&#039;ARTICLE            <\/button>\n          <\/a>\n          <a data-km2-rewarded=\"false\" style=\"font-size: 15px;\" class=\"flex m-auto sm:mr-0 sm:ml-auto\"  href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button id=\"offer-first\" class=\"flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-6 focus:outline-none rounded  disabled:opacity-50\">\n              ACC\u00c9DER \u00c0 L&#039;ARTICLE            <\/button>\n          <\/a>\n        <\/div>\n        <p class=\"text-xs text-gray-500 mt-3 text-center sm:text-right\">\n          Je me reposerai sur mon propre site Web        <\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-1-scaled.jpeg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Transformez votre carri\u00e8re avec des cours de cr\u00e9ation de sourcils\u2026              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    ACC\u00c9DER \u00c0 L&#039;ARTICLE                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je me reposerai sur mon propre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/section><\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Imaginez la possibilit\u00e9 d&#039;accentuer votre beaut\u00e9 naturelle, en mettant en valeur vos caract\u00e9ristiques uniques, le tout avec une simple touche de cr\u00e9ativit\u00e9. C&#039;est ce que propose le design des sourcils.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Alors poursuivez votre lecture pendant que nous plongeons dans le monde passionnant du stylisme des sourcils, explorons ses techniques, ses opportunit\u00e9s d&#039;apprentissage et comment ce voyage peut ouvrir les portes d&#039;une carri\u00e8re passionnante.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-primeiros-passos-para-iniciar-na-carreira-de-designer-de-sobrancelhas\">Premiers pas pour d\u00e9marrer une carri\u00e8re de designer de sourcils<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Les premi\u00e8res \u00e9tapes pour devenir un artiste du sourcil \u00e0 succ\u00e8s sont cruciales, et nous sommes l\u00e0 pour vous guider sur ce chemin passionnant.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-conhecimento-teorico-cursos\">Connaissances th\u00e9oriques : cours<\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Tout commence par une base solide de connaissances th\u00e9oriques. Autrement dit, pour se d\u00e9marquer en tant que cr\u00e9ateur de sourcils, il est essentiel de comprendre les principes qui se cachent derri\u00e8re cet art.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Cela inclut la compr\u00e9hension des diff\u00e9rents types de sourcils, de leur lien avec les types de visage, des techniques d&#039;\u00e9pilation \u00e0 la cire, de coloration, etc. Les cours de design de sourcils sont donc vos alli\u00e9s.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>De plus, apr\u00e8s avoir suivi un cours de conception de sourcils, vous recevrez un certificat prouvant votre comp\u00e9tence, essentielle pour renforcer votre cr\u00e9dibilit\u00e9 sur le march\u00e9.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-conhecimento-pratico\">Connaissance pratique<\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Dans le monde du stylisme des sourcils, la pratique est la cl\u00e9 du succ\u00e8s. Apr\u00e8s tout, c\u2019est l\u2019application pratique qui transforme la th\u00e9orie en comp\u00e9tence. Au fur et \u00e0 mesure que vous progressez, il est essentiel de mettre en pratique les techniques que vous apprenez.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Pensez donc \u00e0 offrir vos services gratuitement \u00e0 vos amis, \u00e0 votre famille ou \u00e0 faire du b\u00e9n\u00e9volat lors d&#039;\u00e9v\u00e9nements locaux. Plus vous acquerrez d\u2019exp\u00e9rience pratique, plus vous aurez confiance en vous et plus votre travail sera impressionnant.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h3 id=\"h-atualize-se-sobre-tendencias\">Le point sur les tendances<\/h3>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Le monde de la mode et de la beaut\u00e9 est en constante \u00e9volution et le style des sourcils ne fait pas exception. Par cons\u00e9quent, pour r\u00e9ussir en tant que cr\u00e9ateur de sourcils, il est essentiel de rester \u00e0 jour.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>En fin de compte, cela peut \u00eatre r\u00e9alis\u00e9 en participant \u00e0 des ateliers, \u00e0 des cours de remise \u00e0 niveau et en suivant des sites Web de beaut\u00e9 pertinents.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-melhores-cursos-para-aprender-design-de-sobrancelhas\">Meilleurs cours pour apprendre le design des sourcils<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-3-1024x683.jpeg\" alt=\"\" class=\"w-full object-cover object-center border mx-auto wp-image-12234\" width=\"800\" height=\"384\"\/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Votre carri\u00e8re dans la conception de sourcils commence ici. Source : Adobe Stock<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Enfin, vous \u00eates-vous d\u00e9j\u00e0 demand\u00e9 comment sont cr\u00e9\u00e9s ces sourcils impeccables et parfaitement dessin\u00e9s ? La r\u00e9ponse r\u00e9side dans des mains comp\u00e9tentes et des connaissances sp\u00e9cialis\u00e9es.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Si vous \u00eates pr\u00eat \u00e0 plonger dans le monde de la beaut\u00e9 et \u00e0 d\u00e9couvrir les secrets de la conception des sourcils, vous devez acc\u00e9der \u00e0 l&#039;article ci-dessous.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Dans cet article, nous vous d\u00e9voilerons les meilleurs cours qui vous aideront \u00e0 ma\u00eetriser cet art fascinant et \u00e0 transformer les visages de vos clients en v\u00e9ritables \u0153uvres d&#039;art.&nbsp;<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>N&#039;attendez plus ! Apr\u00e8s tout, la beaut\u00e9 attend que vous la r\u00e9v\u00e9liez.<\/p>\n<\/div><div class=\"wp-block-lazyblock-credit-card lazyblock-credit-card-EbbgY\"><section class=\"credit-card mx-5 sm:mx-0 text-gray-600 body-font  my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n  <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n    <div class=\"w-24 h-full\"><\/div>\n  <\/div>\n  <div class=\"container px-5 sm:px-0 py-6 mx-auto\" data-anchor-target=\"lazyBlock\">\n    <div class=\"flex flex-wrap mx-auto\">\n      <a class=\"lg:w-2\/5 w-full lg:pl-6 mt-6 lg:mt-0\" href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\" data-analytics-label=\"creditCardImage\" data-action=\"analytics#trackCTA\" >\n        <img class=\"w-full h-64 object-cover object-center rounded\" loading=\"lazy\" alt=\"card\" style=\"height: 190px;\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-2-scaled.jpeg\">\n      <\/a>\n      <div class=\"lg:w-3\/5 w-full lg:pl-6 mt-6 lg:mt-0\">\n        <h2 class=\"text-sm title-font text-gray-500 tracking-widest uppercase\">\n          Article        <\/h2>\n        <h1 class=\"text-gray-900 text-3xl title-font font-medium mb-1\">\n          Cours de conception de sourcils        <\/h1>\n        <div class=\"flex mb-4 justify-center sm:justify-start\">\n          \n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              cours de designer            <\/span>\n                      <span class=\"inline-block py-1 px-2 rounded text-xs font-medium tracking-widest uppercase mr-2\">\n              les sourcils            <\/span>\n                    \n        <\/div>\n        <p class=\"leading-relaxed\">\n          Affinez vos comp\u00e9tences et r\u00e9ussissez avec les cours de conception de sourcils.        <\/p>\n        <div class=\"flex mt-6 items-center pb-5 border-b-2 border-gray-100 mb-5\">\n          \n        <\/div>\n        <div class=\"flex\">\n          <a data-km2-rewarded=\"true\" style=\"font-size: 13px;\" class=\"hidden animate-fade-in flex m-auto sm:mr-0 sm:ml-auto\"  href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button class=\"uppercase flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-4 focus:outline-none rounded  disabled:opacity-50\">\n              VOIR LES COURS            <\/button>\n          <\/a>\n          <a data-km2-rewarded=\"false\" style=\"font-size: 15px;\" class=\"flex m-auto sm:mr-0 sm:ml-auto\"  href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\" data-analytics-label=\"creditCardButton\" data-action=\"analytics#trackCTA\"  >\n            <button id=\"offer-first\" class=\"flex m-auto sm:mr-0 sm:ml-auto border-0 py-2 px-6 focus:outline-none rounded  disabled:opacity-50\">\n              VOIR LES COURS            <\/button>\n          <\/a>\n        <\/div>\n        <p class=\"text-xs text-gray-500 mt-3 text-center sm:text-right\">\n          Je me reposerai sur mon propre site Web        <\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-2-scaled.jpeg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Am\u00e9liorez vos comp\u00e9tences et r\u00e9ussissez avec\u2026              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/fr\/curso-de-designer-de-sobrancelhas\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    VOIR LES COURS                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Je me reposerai sur mon propre site Web              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/section><\/div>","protected":false},"excerpt":{"rendered":"<p>Ma\u00eetrisez l&#039;art de perfectionner et de sublimer la beaut\u00e9 naturelle de votre visage gr\u00e2ce aux techniques de modelage et de coloration ! Continuez \u00e0 lire et d\u00e9couvrez comment devenir un cr\u00e9ateur de sourcils \u00e0 succ\u00e8s, avec les meilleurs cours dans le domaine.<\/p>","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[281],"tags":[680,678,679],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.7 (Yoast SEO v19.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Design de sobrancelhas: como se tornar uma profissional na \u00e1rea<\/title>\n<meta name=\"description\" content=\"Descubra os segredos do design de sobrancelhas e transforme sua carreira! Aprenda com profissionais e domine t\u00e9cnicas avan\u00e7adas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/senhorcursos.com\/fr\/design-de-sobrancelhas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea\" \/>\n<meta property=\"og:description\" content=\"Descubra os segredos do design de sobrancelhas e transforme sua carreira! Aprenda com profissionais e domine t\u00e9cnicas avan\u00e7adas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/senhorcursos.com\/fr\/design-de-sobrancelhas\/\" \/>\n<meta property=\"og:site_name\" content=\"Senhor Cursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-11T12:15:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-13T19:39:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Saes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/senhorcursos.com\/#website\",\"url\":\"https:\/\/senhorcursos.com\/\",\"name\":\"Senhor Cursos\",\"description\":\"Os melhores cursos, concursos e vagas de empregos para voc\u00ea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/senhorcursos.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#primaryimage\",\"url\":\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg\",\"contentUrl\":\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#webpage\",\"url\":\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/\",\"name\":\"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea\",\"isPartOf\":{\"@id\":\"https:\/\/senhorcursos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#primaryimage\"},\"datePublished\":\"2023-09-11T12:15:53+00:00\",\"dateModified\":\"2023-09-13T19:39:15+00:00\",\"author\":{\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/2af0240749162c7d03634bd242d911d3\"},\"description\":\"Descubra os segredos do design de sobrancelhas e transforme sua carreira! Aprenda com profissionais e domine t\u00e9cnicas avan\u00e7adas.\",\"breadcrumb\":{\"@id\":\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/senhorcursos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/2af0240749162c7d03634bd242d911d3\",\"name\":\"Aline Saes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"caption\":\"Aline Saes\"},\"url\":\"https:\/\/senhorcursos.com\/fr\/author\/aline-saes-rodriguesgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea","description":"Descubra os segredos do design de sobrancelhas e transforme sua carreira! Aprenda com profissionais e domine t\u00e9cnicas avan\u00e7adas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/senhorcursos.com\/fr\/design-de-sobrancelhas\/","og_locale":"fr_FR","og_type":"article","og_title":"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea","og_description":"Descubra os segredos do design de sobrancelhas e transforme sua carreira! Aprenda com profissionais e domine t\u00e9cnicas avan\u00e7adas.","og_url":"https:\/\/senhorcursos.com\/fr\/design-de-sobrancelhas\/","og_site_name":"Senhor Cursos","article_published_time":"2023-09-11T12:15:53+00:00","article_modified_time":"2023-09-13T19:39:15+00:00","og_image":[{"url":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aline Saes","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/senhorcursos.com\/#website","url":"https:\/\/senhorcursos.com\/","name":"Senhor Cursos","description":"Os melhores cursos, concursos e vagas de empregos para voc\u00ea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/senhorcursos.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#primaryimage","url":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg","contentUrl":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2023\/09\/design-de-sobrancelhas-4-1024x448.jpeg"},{"@type":"WebPage","@id":"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#webpage","url":"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/","name":"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea","isPartOf":{"@id":"https:\/\/senhorcursos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#primaryimage"},"datePublished":"2023-09-11T12:15:53+00:00","dateModified":"2023-09-13T19:39:15+00:00","author":{"@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/2af0240749162c7d03634bd242d911d3"},"description":"Descubra os segredos do design de sobrancelhas e transforme sua carreira! Aprenda com profissionais e domine t\u00e9cnicas avan\u00e7adas.","breadcrumb":{"@id":"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/senhorcursos.com\/design-de-sobrancelhas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/senhorcursos.com\/design-de-sobrancelhas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/senhorcursos.com\/"},{"@type":"ListItem","position":2,"name":"Design de sobrancelhas: como se tornar uma profissional na \u00e1rea"}]},{"@type":"Person","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/2af0240749162c7d03634bd242d911d3","name":"Aline Saes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","caption":"Aline Saes"},"url":"https:\/\/senhorcursos.com\/fr\/author\/aline-saes-rodriguesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts\/12230"}],"collection":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/comments?post=12230"}],"version-history":[{"count":0,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/posts\/12230\/revisions"}],"wp:attachment":[{"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/media?parent=12230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/categories?post=12230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senhorcursos.com\/fr\/wp-json\/wp\/v2\/tags?post=12230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}