{"id":3283,"date":"2022-12-28T12:00:00","date_gmt":"2022-12-28T12:00:00","guid":{"rendered":"https:\/\/senhorcursos.com\/?p=3283"},"modified":"2022-12-29T00:49:01","modified_gmt":"2022-12-29T00:49:01","slug":"prova-de-titulos","status":"publish","type":"post","link":"https:\/\/senhorcursos.com\/es\/prova-de-titulos\/","title":{"rendered":"Prueba de cualificaciones: \u00bfqu\u00e9 es y c\u00f3mo funciona en el proceso de selecci\u00f3n?"},"content":{"rendered":"<!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-confira-o-nosso-guia-completo-sobre-este-assunto\">Consulta nuestra gu\u00eda completa sobre este tema.<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large\"><img width=\"1024\" height=\"683\" loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg\" alt=\"Mulher com roupa de gradua\u00e7\u00e3o pensando\" class=\"w-full object-cover object-center border mx-auto wp-image-3284\" title=\"Prueba de cualificaciones\" srcset=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg 1024w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-300x200.jpg 300w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-768x512.jpg 768w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1536x1024.jpg 1536w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Descubre c\u00f3mo las cualificaciones pueden ayudarte a conseguir un empleo en las oposiciones a la funci\u00f3n p\u00fablica. Fuente: Freepik.<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La evaluaci\u00f3n de las cualificaciones es una etapa presente en algunos ex\u00e1menes de ingreso al servicio p\u00fablico. Esto puede ser de gran ayuda o, por el contrario, perjudicar al candidato durante el proceso de selecci\u00f3n.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>\u00bfSabes c\u00f3mo funciona esta fase y qu\u00e9 se necesita para conseguir puntos en ella?&nbsp;<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-Z10aNxW\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/es\/concurso-de-nivel-superior\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"Competencia de nivel superior\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/11\/graduate-6671173_1920.jpg\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/es\/concurso-de-nivel-superior\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"Competencia de nivel superior\">\n            Competencia de nivel superior        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            Averigua qu\u00e9 puestos requieren un t\u00edtulo universitario en un examen de servicio p\u00fablico.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/es\/concurso-de-nivel-superior\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuar leyendo            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/es\/concurso-de-nivel-superior\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/11\/graduate-6671173_1920.jpg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Competencia de nivel superior              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/es\/concurso-de-nivel-superior\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuar leyendo                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Permanecer\u00e1s en el mismo lugar              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>En este texto, le proporcionaremos m\u00e1s informaci\u00f3n sobre este tema y le ayudaremos a comprender c\u00f3mo funcionan los ex\u00e1menes de certificaci\u00f3n.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Por lo tanto, si est\u00e1s preparando ex\u00e1menes para el servicio p\u00fablico y tienes alguna pregunta sobre este tema, \u00a1aseg\u00farate de leer nuestro texto hasta el final!<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-o-que-e-prova-de-titulos\">\u00bfQu\u00e9 es una prueba de cualificaciones?<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large\"><img width=\"1024\" height=\"683\" loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/serious-indian-graduate-graduation-robe-with-crossed-arms-looking-forward-1024x683.jpg\" alt=\"Homem com roupa de gradua\u00e7\u00e3o\" class=\"w-full object-cover object-center border mx-auto wp-image-3285\" title=\"Prueba de cualificaciones\" srcset=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/serious-indian-graduate-graduation-robe-with-crossed-arms-looking-forward-1024x683.jpg 1024w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/serious-indian-graduate-graduation-robe-with-crossed-arms-looking-forward-300x200.jpg 300w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/serious-indian-graduate-graduation-robe-with-crossed-arms-looking-forward-768x512.jpg 768w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/serious-indian-graduate-graduation-robe-with-crossed-arms-looking-forward-1536x1024.jpg 1536w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/serious-indian-graduate-graduation-robe-with-crossed-arms-looking-forward-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Este es un paso en la evaluaci\u00f3n de un curr\u00edculum. Fuente: Freepik.<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La evaluaci\u00f3n de las cualificaciones es una fase de clasificaci\u00f3n presente en algunos ex\u00e1menes de acceso a la funci\u00f3n p\u00fablica. Su finalidad es garantizar que el candidato con las mejores cualificaciones obtenga el puesto.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Debe realizarse despu\u00e9s de las pruebas y rondas eliminatorias de la competici\u00f3n. Por lo tanto, es una etapa que otorga nuevos puntos al candidato, pero no elimina a ning\u00fan competidor que no cumpla los requisitos.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Por \u00faltimo, los requisitos aceptados y la forma de realizar esta prueba pueden variar seg\u00fan la convocatoria. Por lo tanto, es importante prestar atenci\u00f3n a la informaci\u00f3n del anuncio del examen.<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-Z1GPdau\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/es\/como-estudar-para-concurso\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"C\u00f3mo estudiar para un examen de oposici\u00f3n\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/young-attractive-smiling-student-showing-thumb-up-outdoors-on-campus-at-the-university-scaled.jpg\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/es\/como-estudar-para-concurso\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"C\u00f3mo estudiar para un examen de oposici\u00f3n\">\n            C\u00f3mo estudiar para un examen de oposici\u00f3n        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            Nuestra gu\u00eda puede ayudarte a prepararte para los ex\u00e1menes; obt\u00e9n m\u00e1s informaci\u00f3n aqu\u00ed.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/es\/como-estudar-para-concurso\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuar leyendo            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/es\/como-estudar-para-concurso\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/young-attractive-smiling-student-showing-thumb-up-outdoors-on-campus-at-the-university-scaled.jpg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                C\u00f3mo estudiar para un examen de oposici\u00f3n              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/es\/como-estudar-para-concurso\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuar leyendo                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Permanecer\u00e1s en el mismo lugar              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-como-funciona-a-prova-de-titulos\">\u00bfC\u00f3mo funciona la evaluaci\u00f3n de las cualificaciones?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La evaluaci\u00f3n de las credenciales acad\u00e9micas otorgar\u00e1 puntos por cada una de ellas. Por lo tanto, es posible mejorar la posici\u00f3n en el ranking si se cuenta con una maestr\u00eda, un doctorado, publicaciones cient\u00edficas, etc.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Al mismo tiempo, la experiencia en el sector durante un cierto per\u00edodo o incluso los certificados de cursos cortos tambi\u00e9n pueden considerarse cualificaciones.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Por lo tanto, la evaluaci\u00f3n de cualificaciones funciona como una segunda evaluaci\u00f3n que se realiza despu\u00e9s del examen de ingreso al servicio p\u00fablico. En esta evaluaci\u00f3n, los candidatos con mayor experiencia o estudios en el \u00e1rea obtienen mejores resultados.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-quais-concursos-exigem-essa-prova\">\u00bfQu\u00e9 competiciones requieren esta prueba?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Inicialmente, la evaluaci\u00f3n de las credenciales acad\u00e9micas era com\u00fan en los ex\u00e1menes de ingreso al servicio p\u00fablico en el \u00e1mbito jur\u00eddico. Sin embargo, en la actualidad tambi\u00e9n se utiliza en los procesos de selecci\u00f3n de docentes, m\u00e9dicos, jueces y otros profesionales.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Dado que la demanda de profesionales cualificados sigue creciendo, tambi\u00e9n aumenta el n\u00famero de oposiciones a la funci\u00f3n p\u00fablica que incluyen esta fase en el proceso de selecci\u00f3n. Por lo tanto, recomendamos a los candidatos que se preparen para esta prueba, independientemente de su especialidad.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-quais-sao-os-documentos-aceitos-na-prova\">\u00bfQu\u00e9 documentos se aceptan para el examen?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Los documentos aceptados para la evaluaci\u00f3n de las cualificaciones se describir\u00e1n en el anuncio p\u00fablico que recoge las bases del examen de oposici\u00f3n. En cada caso, podr\u00e1n aceptarse diferentes documentos justificativos.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Sin embargo, entre los documentos est\u00e1ndar que se suelen solicitar se encuentran los diplomas de estudios de posgrado. Por ejemplo: m\u00e1ster, doctorado, especializaci\u00f3n o MBA.\u00a0<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Asimismo, puede ser necesario presentar comprobantes de publicaciones como libros, art\u00edculos cient\u00edficos y participaci\u00f3n en eventos acad\u00e9micos. En este caso, las instrucciones para obtener la documentaci\u00f3n se proporcionar\u00e1n en la convocatoria.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Finalmente, si necesita presentar un documento que acredite su experiencia en el sector, lea atentamente las bases del concurso para saber c\u00f3mo presentarlo.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-como-e-feita-a-prova-de-titulos\">\u00bfC\u00f3mo se realiza la evaluaci\u00f3n de las cualificaciones?<\/h2>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Tras la primera fase del proceso de selecci\u00f3n, los candidatos que la superen ser\u00e1n sometidos a una evaluaci\u00f3n de cualificaciones. Por lo tanto, ser\u00e1 necesario presentar justificantes de experiencia o cursos realizados.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Las bases de la convocatoria le informar\u00e1n sobre la puntuaci\u00f3n que otorga cada certificado. Asimismo, puede existir un l\u00edmite m\u00e1ximo de puntuaci\u00f3n que un candidato puede obtener con su documentaci\u00f3n acreditativa.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Por \u00faltimo, es importante presentar los documentos antes de la fecha l\u00edmite indicada en la convocatoria y en el formato correcto. Esto ayudar\u00e1 a evitar errores y garantizar\u00e1 que sus cualificaciones no sean reconocidas en este proceso.<\/p>\n<\/div><!--advertisement--><div class=\"mx-5 sm:mx-0 sm:text-3xl text-2xl font-medium title-font mb-4 text-gray-900 text-left\">\n<h2 id=\"h-essa-prova-pode-eliminar-um-candidato-do-concurso\">\u00bfPodr\u00eda esta prueba descalificar a un candidato de la competici\u00f3n?<\/h2>\n<\/div><!--image--><div class=\"px-5 sm:px-0 sm:w-[800px] sm:ml-[50%] sm:-translate-x-2\/4 rounded-lg overflow-hidden mb-5 text-center\">\n<figure class=\"wp-block-image size-large\"><img width=\"1024\" height=\"643\" loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/hand-writing-paper-with-pen-1024x643.jpg\" alt=\"Pessoa fazendo prova\" class=\"w-full object-cover object-center border mx-auto wp-image-3286\" title=\"Prueba de cualificaciones\" srcset=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/hand-writing-paper-with-pen-1024x643.jpg 1024w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/hand-writing-paper-with-pen-300x188.jpg 300w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/hand-writing-paper-with-pen-768x482.jpg 768w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/hand-writing-paper-with-pen-1536x964.jpg 1536w, https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/hand-writing-paper-with-pen-2048x1286.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"mt-5 text-xs text-center border-b pb-4\" >Obt\u00e9n m\u00e1s informaci\u00f3n sobre c\u00f3mo funciona esta prueba. Fuente: Freepik.<\/figcaption><\/figure>\n<\/div><!--image--><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>La evaluaci\u00f3n de las cualificaciones tiene \u00fanicamente fines de clasificaci\u00f3n; es decir, otorgar\u00e1 m\u00e1s puntos y modificar\u00e1 las puntuaciones de los candidatos, pero no eliminar\u00e1 a ninguno de los solicitantes.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Por lo tanto, las personas que obtuvieron una puntuaci\u00f3n baja en la parte objetiva o de ensayo de la primera etapa del proceso de selecci\u00f3n pueden avanzar por delante de otros candidatos si poseen numerosas cualificaciones.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Al mismo tiempo, dado que nadie ser\u00e1 eliminado si no obtiene puntuaci\u00f3n en esta etapa, es posible recibir la aprobaci\u00f3n bas\u00e1ndose \u00fanicamente en las puntuaciones de la primera etapa.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Por lo tanto, analiza tu situaci\u00f3n y elabora un plan. Si tienes muchas cualificaciones, quiz\u00e1 no tengas que preocuparte tanto por el examen; en cambio, si no tienes ninguna, aseg\u00farate de obtener tu plaza cuanto antes.<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Si tienes problemas para aprobar ex\u00e1menes de oposici\u00f3n, \u00a1una buena idea podr\u00eda ser usar la t\u00e9cnica del &quot;examen de escalera&quot;! \u00bfSabes c\u00f3mo funciona o qu\u00e9 significa el t\u00e9rmino?<\/p>\n<\/div><div class=\"mx-5 sm:mx-0 prose leading-relaxed text-lg mb-5 text-left wp-paragraph\">\n<p>Lea el texto enlazado a continuaci\u00f3n sobre este tema para descubrir la informaci\u00f3n m\u00e1s importante e implementar esta estrategia.<\/p>\n<\/div><div class=\"wp-block-lazyblock-cta lazyblock-cta-Z13Np4P\">\n  <section class=\"cta mx-5 sm:mx-0 text-gray-600 body-font my-10 border-gray-200 border-b border-l border-r sm:border-0\">\n    <div class=\"h-1 bg-gray-200 rounded overflow-hidden\">\n      <div class=\"w-24 h-full\"><\/div>\n    <\/div>\n    <div class=\"container px-5 pt-6 pb-6 mx-auto flex flex-wrap\" data-anchor-target=\"lazyBlock\">    \n    \n              <a class=\"flex flex-wrap content-center w-full mb-4 md:hidden\" href=\"https:\/\/senhorcursos.com\/es\/concurso-escada\/\"  data-analytics-label=\"ctaImage\" data-action=\"analytics#trackCTA\" aria-label=\"Competici\u00f3n por escaleras: \u00bfqu\u00e9 es?\">\n          <div class=\"m-auto float-none\">\n            <img loading=\"lazy\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/11\/a-man-is-writing-signing-on-a-paper-focused-on-a-hand-with-pen-1-scaled.jpg\" alt=\"\">\n          <\/div>\n        <\/a>\n            <h2 class=\"w-full sm:text-3xl text-2xl text-gray-900 font-medium title-font mb-2 text-center md:text-left md:w-2\/5\">\n        <a href=\"https:\/\/senhorcursos.com\/es\/concurso-escada\/\" data-analytics-label=\"ctaTitle\" data-action=\"analytics#trackCTA\" aria-label=\"Competici\u00f3n por escaleras: \u00bfqu\u00e9 es?\">\n            Competici\u00f3n por escaleras: \u00bfqu\u00e9 es?        <\/a>\n      <\/h2>\n      <div class=\"w-full md:w-3\/5 md:pl-6\">\n        <p class=\"text-center md:text-left leading-relaxed text-base\">\n            Descubre la t\u00e9cnica utilizada por muchos aspirantes a ex\u00e1menes para obtener una calificaci\u00f3n aprobatoria m\u00e1s sencilla.        <\/p>\n        <div class=\"flex mt-6 w-full flex-1 justify-center ml-auto md:mt-4 md:justify-start\" style=\"font-weight: bold;\">\n          <a class=\"inline-flex items-center\" href=\"https:\/\/senhorcursos.com\/es\/concurso-escada\/\"  data-analytics-label=\"ctaButton\" data-action=\"analytics#trackCTA\" >\n            Continuar leyendo            <svg fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" class=\"w-4 h-4 ml-2\" viewbox=\"0 0 24 24\">\n              <path d=\"M5 12h14M12 5l7 7-7 7\"><\/path>\n            <\/svg>\n          <\/a>\n        <\/div>\n      <\/div>  \n          \n    <\/div>\n      <script type=\"module\"> function waitFor(conditionFunction) { const poll = resolve => { if(conditionFunction()) resolve(); else setTimeout(_ => poll(resolve), 400); }; return new Promise(poll); } import { Application, Controller } from \"\/wp-content\/themes\/twentytwentyone\/assets\/js\/stimulus.min.js\"; let Stimulus = Application.start(); Stimulus.register(\"anchor\", class extends Controller { static get targets() { return [ \"lazyBlock\", \"lazyBlockAnchor\" ]; } initialize() { this.active = false; this.passed = false; this.closed = false; this.anchorViews = 0; this.boundOnShowAnchor = this.onShowAnchor.bind(this); window.anchorReady = window.anchorReady || false; waitFor(_ => (window.scrollY > this.getHeightBlock() && !this.active)) .then(_ => { !window.anchorReady? this.visible() : ''; window.anchorReady = true; }); if (document.getElementById('landing')) { setTimeout(() => { !window.anchorReady ? this.visible() : ''; window.anchorReady = true; }, 1 * 30000); }; } connect() { this.onShowAnchor(); document.addEventListener(\"scroll\", this.boundOnShowAnchor); } disconnect() { document.removeEventListener(\"scroll\", this.boundOnShowAnchor); } visible() { if (document.getElementById('av-offerwall__wrapper')) { setTimeout(() => this.visible(), 20000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 100) { setTimeout(() => this.visible(), 1000); return; } if (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10) { this.getAnchorElement().style.marginBottom = '60px'; } if (document.querySelector('[data-anchor-shown=\"true\"]') && document.querySelector('[data-anchor-shown=\"true\"]').style.bottom === '0px') { setTimeout(() => this.visible(), 1000); return; } if (!window.km2AnchorReady) { this.active = true; \/*this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-down');*\/ \/*this.getAnchorElement().classList.add('animate-show-up');*\/ \/*setTimeout(() => {*\/ \/*this.getAnchorElement().style.animation = \"\";*\/ this.getAnchorElement().classList.add('animate-show-up'); this.getAnchorElement().classList.remove('hidden'); this.setAnchorViews(this.anchorViews+1); setTimeout(() => this.closeAnchor(), 20000); waitFor(_ => (document.getElementById('av-fixed__bottomWrapper') && document.getElementById('av-fixed__bottomWrapper').style.display !== 'none' && document.getElementById('av-fixed__bottomWrapper').getBoundingClientRect().height > 10 && this.getAnchorElement().style.marginBottom !== '60px')) .then(_ => { this.closeAnchor(); }); this.active = false; \/*}, 10);*\/ } } invisible() { this.active = true; this.getAnchorElement().style.animation = \"none\"; this.getAnchorElement().classList.remove('animate-show-up'); this.getAnchorElement().classList.add('animate-show-down'); setTimeout(() => { this.getAnchorElement().style.animation = \"\"; setTimeout(() => { this.getAnchorElement().classList.add('hidden'); this.active = false; }, 800); }, 10); } onShowAnchor() { let anchorReady = false;  \/*if (!this.active && !anchorReady) { if (this.getAnchorViews() <= 3) { if (window.scrollY > this.getHeightBlock()) { if (!this.passed && !this.closed) { this.visible(); this.passed = true; } } else { if (this.passed) { this.invisible(); this.passed = false; } } } else { if (!this.getAnchorElement().classList.contains('close')) { this.getAnchorElement().classList.add('close'); if (window.scrollY < this.getHeightBlock()) { this.invisible(); } } } }*\/ } closeAnchor() { if (this.closed) return; this.invisible(); this.getAnchorElement().classList.add('close'); this.closed = true; } getAnchorElement() { return this.lazyBlockAnchorTargets[0]; } getAnchorViews() { this.anchorViews = parseInt(sessionStorage.getItem(\"anchorViews\")) >= 1 ? parseInt(sessionStorage.getItem(\"anchorViews\")) : 0; return this.anchorViews; } setAnchorViews(views) { sessionStorage.setItem(\"anchorViews\", views); } getHeightBlock() { return this.lazyBlockTarget.offsetTop + this.lazyBlockTarget.offsetHeight - 110; } }) <\/script>  <div data-anchor-target=\"lazyBlockAnchor\" class=\"fixed w-full sm:w-96 px-3 py-2 bottom-0 left-0 hidden\" style=\"z-index: 999999;\" name=\"lazyBlockAnchor\">\n    <div class=\"grid justify-items-stretch\">        \n              <div class=\"relative justify-self-end top-4 -right-2\">\n          <button data-no-translation class=\"bg-white text-md font-medium text-center rounded-full h-7 w-7 border-2\" data-analytics-label=\"anchorCloseAnchor\" data-action=\"anchor#closeAnchor\" style=\"z-index: 999999;\">\n            X\n          <\/button>\n        <\/div>\n        <div class=\"justify-self-auto flex flex-col h-32 bg-white border-solid border-2 shadow-md rounded-md\">\n          <div class=\"flex my-0 h-full\">\n            <div class=\"w-2\/5 p-1 ml-2 mt-2 w-full\">\n              <a href=\"https:\/\/senhorcursos.com\/es\/concurso-escada\/\"  data-analytics-label=\"anchorImage\" data-action=\"analytics#trackCTA\">          \n                <img loading=\"lazy\" alt=\"card\" class=\"w-full object-cover h-24 object-center rounded justify-self-auto border-2 border-gray-100\" src=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/11\/a-man-is-writing-signing-on-a-paper-focused-on-a-hand-with-pen-1-scaled.jpg\">          \n              <\/a>\n            <\/div>\n            <div class=\"w-3\/5 my-2\">\n              <p class=\"px-4 text-center text-xs h-1\/2\">\n                Competici\u00f3n por escaleras: \u00bfqu\u00e9 es?              <\/p>\n              <a href=\"https:\/\/senhorcursos.com\/es\/concurso-escada\/\"  data-analytics-label=\"anchorButton\" data-action=\"analytics#trackCTA\" >\n                <button class=\"flex w-5\/6 m-auto mt-2 border-0 py-1 px-3 focus:outline-none rounded\">                \n                  <p class=\"text-center w-full\" style=\"font-size: 0.67rem;\">\n                    Continuar leyendo                  <\/p>\n                <\/button>\n              <\/a>\n              <p class=\"text-gray-500 text-center mt-1\" style=\"font-size: 0.50rem;\">\n                Permanecer\u00e1s en el mismo lugar              <\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n  <\/section>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La evaluaci\u00f3n de cualificaciones es una etapa de clasificaci\u00f3n en la que las personas con m\u00e1s experiencia o estudios en un campo determinado pueden obtener ventaja en un examen de ingreso al servicio p\u00fablico. M\u00e1s informaci\u00f3n aqu\u00ed.<\/p>","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[15,14,268],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.7 (Yoast SEO v19.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso? - Senhor Cursos<\/title>\n<meta name=\"description\" content=\"Nosso texto te ajuda a entender o que \u00e9 prova de t\u00edtulos e o que \u00e9 necess\u00e1rio para pontuar nesta etapa de concurso p\u00fablico!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/senhorcursos.com\/es\/prova-de-titulos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso?\" \/>\n<meta property=\"og:description\" content=\"Nosso texto te ajuda a entender o que \u00e9 prova de t\u00edtulos e o que \u00e9 necess\u00e1rio para pontuar nesta etapa de concurso p\u00fablico!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/senhorcursos.com\/es\/prova-de-titulos\/\" \/>\n<meta property=\"og:site_name\" content=\"Senhor Cursos\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-29T00:49:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Saes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/senhorcursos.com\/#website\",\"url\":\"https:\/\/senhorcursos.com\/\",\"name\":\"Senhor Cursos\",\"description\":\"Os melhores cursos, concursos e vagas de empregos para voc\u00ea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/senhorcursos.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/senhorcursos.com\/prova-de-titulos\/#primaryimage\",\"url\":\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg\",\"contentUrl\":\"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/senhorcursos.com\/prova-de-titulos\/#webpage\",\"url\":\"https:\/\/senhorcursos.com\/prova-de-titulos\/\",\"name\":\"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso? - Senhor Cursos\",\"isPartOf\":{\"@id\":\"https:\/\/senhorcursos.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/senhorcursos.com\/prova-de-titulos\/#primaryimage\"},\"datePublished\":\"2022-12-28T12:00:00+00:00\",\"dateModified\":\"2022-12-29T00:49:01+00:00\",\"author\":{\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2\"},\"description\":\"Nosso texto te ajuda a entender o que \u00e9 prova de t\u00edtulos e o que \u00e9 necess\u00e1rio para pontuar nesta etapa de concurso p\u00fablico!\",\"breadcrumb\":{\"@id\":\"https:\/\/senhorcursos.com\/prova-de-titulos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/senhorcursos.com\/prova-de-titulos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/senhorcursos.com\/prova-de-titulos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/senhorcursos.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2\",\"name\":\"Aline Saes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g\",\"caption\":\"Aline Saes\"},\"url\":\"https:\/\/senhorcursos.com\/es\/author\/aline-saes-rodriguesgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso? - Senhor Cursos","description":"Nosso texto te ajuda a entender o que \u00e9 prova de t\u00edtulos e o que \u00e9 necess\u00e1rio para pontuar nesta etapa de concurso p\u00fablico!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/senhorcursos.com\/es\/prova-de-titulos\/","og_locale":"es_ES","og_type":"article","og_title":"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso?","og_description":"Nosso texto te ajuda a entender o que \u00e9 prova de t\u00edtulos e o que \u00e9 necess\u00e1rio para pontuar nesta etapa de concurso p\u00fablico!","og_url":"https:\/\/senhorcursos.com\/es\/prova-de-titulos\/","og_site_name":"Senhor Cursos","article_published_time":"2022-12-28T12:00:00+00:00","article_modified_time":"2022-12-29T00:49:01+00:00","og_image":[{"url":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aline Saes","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/senhorcursos.com\/#website","url":"https:\/\/senhorcursos.com\/","name":"Senhor Cursos","description":"Os melhores cursos, concursos e vagas de empregos para voc\u00ea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/senhorcursos.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/senhorcursos.com\/prova-de-titulos\/#primaryimage","url":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg","contentUrl":"https:\/\/senhorcursos.com\/wp-content\/uploads\/2022\/12\/dreamy-graduate-woman-smiling-thinking-sitting-with-books-1024x683.jpg"},{"@type":"WebPage","@id":"https:\/\/senhorcursos.com\/prova-de-titulos\/#webpage","url":"https:\/\/senhorcursos.com\/prova-de-titulos\/","name":"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso? - Senhor Cursos","isPartOf":{"@id":"https:\/\/senhorcursos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/senhorcursos.com\/prova-de-titulos\/#primaryimage"},"datePublished":"2022-12-28T12:00:00+00:00","dateModified":"2022-12-29T00:49:01+00:00","author":{"@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2"},"description":"Nosso texto te ajuda a entender o que \u00e9 prova de t\u00edtulos e o que \u00e9 necess\u00e1rio para pontuar nesta etapa de concurso p\u00fablico!","breadcrumb":{"@id":"https:\/\/senhorcursos.com\/prova-de-titulos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/senhorcursos.com\/prova-de-titulos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/senhorcursos.com\/prova-de-titulos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/senhorcursos.com\/"},{"@type":"ListItem","position":2,"name":"Prova de t\u00edtulos: o que \u00e9 e como funciona no concurso?"}]},{"@type":"Person","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/6989a09293507915601500b85bdf70e2","name":"Aline Saes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/senhorcursos.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbba2c3f92032de0d7a091559878aacc?s=96&d=mm&r=g","caption":"Aline Saes"},"url":"https:\/\/senhorcursos.com\/es\/author\/aline-saes-rodriguesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/posts\/3283"}],"collection":[{"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/comments?post=3283"}],"version-history":[{"count":0,"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/posts\/3283\/revisions"}],"wp:attachment":[{"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/media?parent=3283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/categories?post=3283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senhorcursos.com\/es\/wp-json\/wp\/v2\/tags?post=3283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}